{"id":117437,"date":"2025-10-29T13:04:47","date_gmt":"2025-10-29T17:04:47","guid":{"rendered":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/"},"modified":"2026-02-05T11:40:29","modified_gmt":"2026-02-05T15:40:29","slug":"airsole","status":"publish","type":"empleador","link":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/","title":{"rendered":"AIRSOLE SRL"},"content":{"rendered":"<p>Somos una empresa l\u00edder con sede en Santo Domingo y cobertura a nivel nacional, especializada desde 1996 en el dise\u00f1o e instalaci\u00f3n de sistemas de energ\u00eda solar fotovoltaica y almacenamiento, entregando proyectos llave en mano en toda la regi\u00f3n.<\/p>\n<p>Nuestra Cultura:<br \/>\nOperamos en un entorno t\u00e9cnico y din\u00e1mico, donde priman la autonom\u00eda responsable y la excelencia en la ejecuci\u00f3n. Valoramos a profesionales proactivos, comprometidos con la innovaci\u00f3n, el rigor y la obtenci\u00f3n de resultados de calidad.<br \/>\n\u00bfBuscas un desaf\u00edo en un sector en crecimiento y con proyecci\u00f3n nacional? \u00danete a nosotros.<\/p>\n","protected":false},"author":50462,"template":"","class_list":["post-117437","empleador","type-empleador","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIRSOLE SRL | tomaempleo.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIRSOLE SRL | tomaempleo.com\" \/>\n<meta property=\"og:description\" content=\"Somos una empresa l\u00edder con sede en Santo Domingo y cobertura a nivel nacional, especializada desde 1996 en el dise\u00f1o e instalaci\u00f3n de sistemas de energ\u00eda solar fotovoltaica y almacenamiento, entregando proyectos llave en mano en toda la regi\u00f3n. Nuestra Cultura: Operamos en un entorno t\u00e9cnico y din\u00e1mico, donde priman la autonom\u00eda responsable y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/\" \/>\n<meta property=\"og:site_name\" content=\"tomaempleo.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tomaempleos\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T15:40:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tomaempleos\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/\",\"name\":\"AIRSOLE SRL | tomaempleo.com\",\"isPartOf\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\"},\"datePublished\":\"2025-10-29T17:04:47+00:00\",\"dateModified\":\"2026-02-05T15:40:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tomaempleo.com\/dominicana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AIRSOLE SRL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"name\":\"tomaempleo.com\",\"description\":\"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed\",\"publisher\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\"},\"alternateName\":\"tomaempleo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\",\"name\":\"tomaempleo.com\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"contentUrl\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"width\":600,\"height\":600,\"caption\":\"tomaempleo.com\"},\"image\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tomaempleos\",\"https:\/\/x.com\/tomaempleos\",\"https:\/\/www.youtube.com\/@tomaempleo\",\"https:\/\/www.instagram.com\/tomaempleo\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AIRSOLE SRL | tomaempleo.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/","og_locale":"es_ES","og_type":"article","og_title":"AIRSOLE SRL | tomaempleo.com","og_description":"Somos una empresa l\u00edder con sede en Santo Domingo y cobertura a nivel nacional, especializada desde 1996 en el dise\u00f1o e instalaci\u00f3n de sistemas de energ\u00eda solar fotovoltaica y almacenamiento, entregando proyectos llave en mano en toda la regi\u00f3n. Nuestra Cultura: Operamos en un entorno t\u00e9cnico y din\u00e1mico, donde priman la autonom\u00eda responsable y la [&hellip;]","og_url":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/","og_site_name":"tomaempleo.com","article_publisher":"https:\/\/www.facebook.com\/tomaempleos","article_modified_time":"2026-02-05T15:40:29+00:00","twitter_card":"summary_large_image","twitter_site":"@tomaempleos","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/","url":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/","name":"AIRSOLE SRL | tomaempleo.com","isPartOf":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#website"},"datePublished":"2025-10-29T17:04:47+00:00","dateModified":"2026-02-05T15:40:29+00:00","breadcrumb":{"@id":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tomaempleo.com\/dominicana\/empleador\/airsole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tomaempleo.com\/dominicana\/"},{"@type":"ListItem","position":2,"name":"AIRSOLE SRL"}]},{"@type":"WebSite","@id":"https:\/\/tomaempleo.com\/dominicana\/#website","url":"https:\/\/tomaempleo.com\/dominicana\/","name":"tomaempleo.com","description":"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed","publisher":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#organization"},"alternateName":"tomaempleo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tomaempleo.com\/dominicana\/#organization","name":"tomaempleo.com","url":"https:\/\/tomaempleo.com\/dominicana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/","url":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","contentUrl":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","width":600,"height":600,"caption":"tomaempleo.com"},"image":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tomaempleos","https:\/\/x.com\/tomaempleos","https:\/\/www.youtube.com\/@tomaempleo","https:\/\/www.instagram.com\/tomaempleo\/"]}]}},"_links":{"self":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/empleador\/117437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/empleador"}],"about":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/types\/empleador"}],"author":[{"embeddable":true,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/users\/50462"}],"version-history":[{"count":2,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/empleador\/117437\/revisions"}],"predecessor-version":[{"id":118632,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/empleador\/117437\/revisions\/118632"}],"wp:attachment":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/media?parent=117437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}