{"id":110251,"date":"2025-01-04T09:22:17","date_gmt":"2025-01-04T13:22:17","guid":{"rendered":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/"},"modified":"2025-01-29T11:47:09","modified_gmt":"2025-01-29T15:47:09","slug":"enc-de-compras-nacionales-e-internacionales","status":"publish","type":"trabajos","link":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/","title":{"rendered":"Enc. de Compras Nacionales e Internacionales"},"content":{"rendered":"<p>Ambos sexos aplican<br \/>\nGraduado de Ing. Industrial, Adm de Empresas o afines<br \/>\nExperiencia en compras nacionales e internacionales en zona franca *(imprescindible) de 4 a\u00f1os en adelante<br \/>\nBuen dominio del idioma ingl\u00e9s<br \/>\nCapacidad de negociaci\u00f3n<br \/>\nBuenas relaciones humanas<br \/>\nProactivo(a)<br \/>\nDiliegente, sentido de urgencia<br \/>\nResponsable<br \/>\nResidir en Santiago Oeste (preferible)<br \/>\nOfrecemos: sueldo competitivo +beneficios y otros<\/p>\n","protected":false},"author":17234,"template":"","class_list":["post-110251","trabajos","type-trabajos","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enc. de Compras Nacionales e Internacionales | tomaempleo.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enc. de Compras Nacionales e Internacionales | tomaempleo.com\" \/>\n<meta property=\"og:description\" content=\"Ambos sexos aplican Graduado de Ing. Industrial, Adm de Empresas o afines Experiencia en compras nacionales e internacionales en zona franca *(imprescindible) de 4 a\u00f1os en adelante Buen dominio del idioma ingl\u00e9s Capacidad de negociaci\u00f3n Buenas relaciones humanas Proactivo(a) Diliegente, sentido de urgencia Responsable Residir en Santiago Oeste (preferible) Ofrecemos: sueldo competitivo +beneficios y otros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"tomaempleo.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tomaempleos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T15:47:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tomaempleos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/\",\"name\":\"Enc. de Compras Nacionales e Internacionales | tomaempleo.com\",\"isPartOf\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\"},\"datePublished\":\"2025-01-04T13:22:17+00:00\",\"dateModified\":\"2025-01-29T15:47:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tomaempleo.com\/dominicana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enc. de Compras Nacionales e Internacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"name\":\"tomaempleo.com\",\"description\":\"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed\",\"publisher\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\"},\"alternateName\":\"tomaempleo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\",\"name\":\"tomaempleo.com\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"contentUrl\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"width\":600,\"height\":600,\"caption\":\"tomaempleo.com\"},\"image\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tomaempleos\",\"https:\/\/x.com\/tomaempleos\",\"https:\/\/www.youtube.com\/@tomaempleo\",\"https:\/\/www.instagram.com\/tomaempleo\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enc. de Compras Nacionales e Internacionales | tomaempleo.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/","og_locale":"es_ES","og_type":"article","og_title":"Enc. de Compras Nacionales e Internacionales | tomaempleo.com","og_description":"Ambos sexos aplican Graduado de Ing. Industrial, Adm de Empresas o afines Experiencia en compras nacionales e internacionales en zona franca *(imprescindible) de 4 a\u00f1os en adelante Buen dominio del idioma ingl\u00e9s Capacidad de negociaci\u00f3n Buenas relaciones humanas Proactivo(a) Diliegente, sentido de urgencia Responsable Residir en Santiago Oeste (preferible) Ofrecemos: sueldo competitivo +beneficios y otros","og_url":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/","og_site_name":"tomaempleo.com","article_publisher":"https:\/\/www.facebook.com\/tomaempleos","article_modified_time":"2025-01-29T15:47:09+00:00","twitter_card":"summary_large_image","twitter_site":"@tomaempleos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/","url":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/","name":"Enc. de Compras Nacionales e Internacionales | tomaempleo.com","isPartOf":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#website"},"datePublished":"2025-01-04T13:22:17+00:00","dateModified":"2025-01-29T15:47:09+00:00","breadcrumb":{"@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/enc-de-compras-nacionales-e-internacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tomaempleo.com\/dominicana\/"},{"@type":"ListItem","position":2,"name":"Enc. de Compras Nacionales e Internacionales"}]},{"@type":"WebSite","@id":"https:\/\/tomaempleo.com\/dominicana\/#website","url":"https:\/\/tomaempleo.com\/dominicana\/","name":"tomaempleo.com","description":"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed","publisher":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#organization"},"alternateName":"tomaempleo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tomaempleo.com\/dominicana\/#organization","name":"tomaempleo.com","url":"https:\/\/tomaempleo.com\/dominicana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/","url":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","contentUrl":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","width":600,"height":600,"caption":"tomaempleo.com"},"image":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tomaempleos","https:\/\/x.com\/tomaempleos","https:\/\/www.youtube.com\/@tomaempleo","https:\/\/www.instagram.com\/tomaempleo\/"]}]}},"_links":{"self":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos\/110251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos"}],"about":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/types\/trabajos"}],"author":[{"embeddable":true,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/users\/17234"}],"version-history":[{"count":0,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos\/110251\/revisions"}],"wp:attachment":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/media?parent=110251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}