{"id":28690,"date":"2022-11-24T17:35:41","date_gmt":"2022-11-24T21:35:41","guid":{"rendered":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/"},"modified":"2023-11-13T15:18:14","modified_gmt":"2023-11-13T19:18:14","slug":"ingeniero-de-cubicacion","status":"publish","type":"trabajos","link":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/","title":{"rendered":"Ingeniero de Cubicaci\u00f3n"},"content":{"rendered":"<p>Requerimos Ingeniero\/a para dar el soporte oportuno al departamento de presupuesto y al director de proyecto en el control de cubicaci\u00f3n y pago de n\u00f3mina al personal y contratistas.<br \/>\nFunciones y Responsabilidades:<br \/>\nRealizar las mediciones en modelos digital y plano de todos los cap\u00edtulos del proyecto que le sean asignados en coordinaci\u00f3n con los arquitectos e ingenieros del \u00e1rea de arquitectura de la empresa y el ingeniero responsable de presupuestos en la oficina t\u00e9cnica.<br \/>\nColaborar con el ingeniero responsable del presupuesto del proyecto en la confecci\u00f3n de an\u00e1lisis de precios y en la elaboraci\u00f3n del presupuesto en general. Realizar levantamientos y mediciones en obra.<br \/>\nRealizar las cubicaciones con los contratistas y enviar a la oficina principal para revisi\u00f3n luego de ser conciliada con los diferentes contratistas y aprobada por el director de proyecto.<br \/>\nDar soporte para el control del presupuesto del proyecto a la oficina central, de acuerdo con el avance diario del proyecto.<br \/>\nDar seguimiento a los ingenieros de campo para recopilar las solicitudes adicionales realizadas por la supervisi\u00f3n y revisar con el director de proyecto si aplica procesar las mismas en caso de que se le solicite.<br \/>\nDar soporte en general a los procesos del departamento de oficina t\u00e9cnica de la empresa.<br \/>\nIndispensable residir en la zona de B\u00e1varo \u00f3 tener Disponibilidad de traslado a la zona.<br \/>\nRequisitos<br \/>\nExperiencia m\u00ednima de 2 a\u00f1os en Cubicaciones de Obras.<br \/>\nT\u00edtulo universitario: Ingenier\u00eda Civil \/ Arquitecto.<br \/>\nManejo de Autocad.<br \/>\nIndispensable residir en la zona de B\u00e1varo \u00f3 tener Disponibilidad de traslado a la zona.<\/p>\n","protected":false},"author":17438,"template":"","class_list":["post-28690","trabajos","type-trabajos","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ingeniero de Cubicaci\u00f3n | tomaempleo.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingeniero de Cubicaci\u00f3n | tomaempleo.com\" \/>\n<meta property=\"og:description\" content=\"Requerimos Ingeniero\/a para dar el soporte oportuno al departamento de presupuesto y al director de proyecto en el control de cubicaci\u00f3n y pago de n\u00f3mina al personal y contratistas. Funciones y Responsabilidades: Realizar las mediciones en modelos digital y plano de todos los cap\u00edtulos del proyecto que le sean asignados en coordinaci\u00f3n con los arquitectos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/\" \/>\n<meta property=\"og:site_name\" content=\"tomaempleo.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tomaempleos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T19:18:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tomaempleos\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/\",\"name\":\"Ingeniero de Cubicaci\u00f3n | tomaempleo.com\",\"isPartOf\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\"},\"datePublished\":\"2022-11-24T21:35:41+00:00\",\"dateModified\":\"2023-11-13T19:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tomaempleo.com\/dominicana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ingeniero de Cubicaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#website\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"name\":\"tomaempleo.com\",\"description\":\"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed\",\"publisher\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\"},\"alternateName\":\"tomaempleo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#organization\",\"name\":\"tomaempleo.com\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"contentUrl\":\"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg\",\"width\":600,\"height\":600,\"caption\":\"tomaempleo.com\"},\"image\":{\"@id\":\"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tomaempleos\",\"https:\/\/x.com\/tomaempleos\",\"https:\/\/www.youtube.com\/@tomaempleo\",\"https:\/\/www.instagram.com\/tomaempleo\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingeniero de Cubicaci\u00f3n | tomaempleo.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/","og_locale":"es_ES","og_type":"article","og_title":"Ingeniero de Cubicaci\u00f3n | tomaempleo.com","og_description":"Requerimos Ingeniero\/a para dar el soporte oportuno al departamento de presupuesto y al director de proyecto en el control de cubicaci\u00f3n y pago de n\u00f3mina al personal y contratistas. Funciones y Responsabilidades: Realizar las mediciones en modelos digital y plano de todos los cap\u00edtulos del proyecto que le sean asignados en coordinaci\u00f3n con los arquitectos [&hellip;]","og_url":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/","og_site_name":"tomaempleo.com","article_publisher":"https:\/\/www.facebook.com\/tomaempleos","article_modified_time":"2023-11-13T19:18:14+00:00","twitter_card":"summary_large_image","twitter_site":"@tomaempleos","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/","url":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/","name":"Ingeniero de Cubicaci\u00f3n | tomaempleo.com","isPartOf":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#website"},"datePublished":"2022-11-24T21:35:41+00:00","dateModified":"2023-11-13T19:18:14+00:00","breadcrumb":{"@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tomaempleo.com\/dominicana\/trabajos\/ingeniero-de-cubicacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tomaempleo.com\/dominicana\/"},{"@type":"ListItem","position":2,"name":"Ingeniero de Cubicaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/tomaempleo.com\/dominicana\/#website","url":"https:\/\/tomaempleo.com\/dominicana\/","name":"tomaempleo.com","description":"\u00bfBuscas trabajo? Empleos de RD aqu\u00ed","publisher":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#organization"},"alternateName":"tomaempleo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tomaempleo.com\/dominicana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tomaempleo.com\/dominicana\/#organization","name":"tomaempleo.com","url":"https:\/\/tomaempleo.com\/dominicana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/","url":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","contentUrl":"https:\/\/tomaempleo.com\/dominicana\/wp-content\/terd-mediafiles\/logo-tomaempleo.jpg","width":600,"height":600,"caption":"tomaempleo.com"},"image":{"@id":"https:\/\/tomaempleo.com\/dominicana\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tomaempleos","https:\/\/x.com\/tomaempleos","https:\/\/www.youtube.com\/@tomaempleo","https:\/\/www.instagram.com\/tomaempleo\/"]}]}},"_links":{"self":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos\/28690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos"}],"about":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/types\/trabajos"}],"author":[{"embeddable":true,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/users\/17438"}],"version-history":[{"count":0,"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/trabajos\/28690\/revisions"}],"wp:attachment":[{"href":"https:\/\/tomaempleo.com\/dominicana\/wp-json\/wp\/v2\/media?parent=28690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}